{"id":1825,"date":"2019-12-12T15:01:00","date_gmt":"2019-12-12T15:01:00","guid":{"rendered":"https:\/\/www.ldc.com\/co\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/"},"modified":"2020-04-29T11:02:19","modified_gmt":"2020-04-29T09:02:19","slug":"capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor","status":"publish","type":"stories-insight","link":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/","title":{"rendered":"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor"},"content":{"rendered":"\n<p>M\u00e1s conocida por sus tradiciones m\u00edsticas, desiertos dram\u00e1ticos, selvas y monta\u00f1as iridiscentes que se elevan por encima de los 5000 metros, la provincia de Jujuy tambi\u00e9n es una de las m\u00e1s pobres de Argentina.<\/p>\n\n\n\n<p>Cada a\u00f1o, los agricultores locales preparan platos festivos y los entierran en los campos como ofrendas a la Pachamama, la Diosa Andina de la Madre Tierra, esperando que ella los recompense con mejores cosechas y suelos f\u00e9rtiles.<\/p>\n\n\n\n<p>Sin embargo, a muchos pueblos ind\u00edgenas la regi\u00f3n les cuesta alimentar a sus familias, y el cambio clim\u00e1tico, las sequ\u00edas frecuentes y la pobreza extrema obligan a muchas personas a emigrar.<\/p>\n\n\n\n<p>Y asimismo, a pesar del enorme progreso en la lucha contra la pobreza extrema a nivel global, el mundo todav\u00eda tiene dificultades para alimentar a su creciente poblaci\u00f3n, y el hambre vuelve a aumentar, especialmente en las comunidades rurales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-768x1024.jpg\" alt=\"blogh-training-pg02.jpg\" class=\"wp-image-3561\" srcset=\"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-scaled.jpg 768w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-225x300.jpg 225w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-1152x1536.jpg 1152w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-345x460.jpg 345w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-308x410.jpg 308w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/20180126_104448_resized-1-549x732.jpg 549w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>En mayo del 2017, LDC y la Fundaci\u00f3n Louis Dreyfus lanzaron un proyecto para mejorar los medios de vida de 339 agricultores y sus familias en 12 comunidades de la provincia de Jujuy, mediante la instalaci\u00f3n de sistemas innovadores de recolecci\u00f3n de agua y la capacitaci\u00f3n para usarlos, as\u00ed como un sistema de microcr\u00e9dito.<\/p>\n\n\n\n<p>Casi todos los agricultores pertenec\u00edan a pueblos ind\u00edgenas con escaso acceso al agua y bajos ingresos, que produc\u00edan (pero a los que les costaba comercializar) patatas andinas, habas, ma\u00edz, tub\u00e9rculos y qu\u00ednoa.<\/p>\n\n\n\n<p>Implementado entre mayo del 2017 y febrero del 2019, el proyecto ten\u00eda como objetivo mejorar los ingresos de los agricultores a trav\u00e9s del acceso facilitado al agua, aumentar su productividad y apoyar el comercio de sus productos, incluso con los turistas.<\/p>\n\n\n\n<p>Al final del proyecto, casi 1438 personas se hab\u00edan beneficiado directamente de sus acciones, incluidas las familias de 117 ganaderos y otras 222 personas que recibieron peque\u00f1os pr\u00e9stamos.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>IMPACTOS CLAVE<\/strong><br><br>Las subvenciones del microcr\u00e9dito crearon oportunidades en los sectores agroecol\u00f3gico, artesanal y tur\u00edstico, especialmente para las mujeres. El proyecto distribuy\u00f3 95 microcr\u00e9ditos en la regi\u00f3n de la Puna que apoyaron a productores de lana de llama en 6 comunidades, y 185 microcr\u00e9ditos en la regi\u00f3n de Quebrada, principalmente para peque\u00f1os agricultores. Despu\u00e9s de que se pagaran los pr\u00e9stamos (todos excepto en 3 casos, en los que se solicit\u00f3 una extensi\u00f3n), los fondos se prestaron a otros agricultores.<br><br>El proyecto tambi\u00e9n facilit\u00f3 el acceso al agua, a trav\u00e9s de sistemas de recolecci\u00f3n y de irrigaci\u00f3n mediante peque\u00f1os tanques y tuber\u00edas. Esto ayud\u00f3 a aumentar la producci\u00f3n agr\u00edcola, tanto para el consumo humano como animal, lo que permiti\u00f3 a los hogares ser m\u00e1s autosuficientes y aument\u00f3 sus ingresos. Como resultado del proyecto, se implementaron 42 instalaciones de agua nuevas y mejoradas.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>\u00abLa pobreza es un fen\u00f3meno complejo y no siempre se puede atribuir a un solo factor\u00bb, coment\u00f3 Luis Zubizarreta, Director de Relaciones Institucionales para Latinoam\u00e9rica Sur y Oeste en LDC. \u00abEn este caso, trabajamos con las comunidades locales para comprender sus necesidades y luego dise\u00f1amos el proyecto en consecuencia\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p>Al mejorar el acceso al agua a trav\u00e9s de capacitaci\u00f3n y nuevos equipos, el proyecto apoy\u00f3 una agricultura m\u00e1s sustentable tanto para los cultivos de subsistencia como para el ganado, como las llamas, lo que tambi\u00e9n impuls\u00f3 el comercio de lana de llama.<\/p>\n\n\n\n<p>Los peque\u00f1os pr\u00e9stamos tambi\u00e9n ayudaron a los agricultores a aumentar su producci\u00f3n y reforzar sus v\u00ednculos con el turismo local.<\/p>\n\n\n\n<p>\u00abCon proyectos conjuntos como este, tanto la Fundaci\u00f3n como LDC demuestran su compromiso compartido de apoyar a las comunidades rurales remotas en todo el mundo\u00bb, destac\u00f3 Zubizarreta. \u00abEstamos comprometidos a construir un futuro sustentable, y nos enorgullece haber contribuido con esto en la regi\u00f3n de Jujuy\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"690\" height=\"176\" src=\"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/blog-training-icons-1.png\" alt=\"blog-training-icons.png\" class=\"wp-image-3562\" srcset=\"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/blog-training-icons-1.png 690w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/blog-training-icons-1-300x77.png 300w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/blog-training-icons-1-670x171.png 670w, https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/blog-training-icons-1-560x143.png 560w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s conocida por sus tradiciones m\u00edsticas, desiertos dram\u00e1ticos, selvas y monta\u00f1as iridiscentes que se elevan por encima de los 5000 metros, la provincia de Jujuy tambi\u00e9n es una de las m\u00e1s pobres de Argentina. Cada a\u00f1o, los agricultores locales preparan platos festivos y los entierran en los campos como ofrendas a la Pachamama, la Diosa [&hellip;]<\/p>\n","protected":false},"featured_media":1826,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1825","stories-insight","type-stories-insight","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor || Louis Dreyfus Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s conocida por sus tradiciones m\u00edsticas, desiertos dram\u00e1ticos, selvas y monta\u00f1as iridiscentes que se elevan por encima de los 5000 metros, la provincia de Jujuy tambi\u00e9n es una de las m\u00e1s pobres de Argentina. Cada a\u00f1o, los agricultores locales preparan platos festivos y los entierran en los campos como ofrendas a la Pachamama, la Diosa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-29T09:02:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/\",\"url\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/\",\"name\":\"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor || Louis Dreyfus Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg\",\"datePublished\":\"2019-12-12T15:01:00+00:00\",\"dateModified\":\"2020-04-29T09:02:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg\",\"width\":506,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/es\\\/stories-insights\\\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stories & Insights\",\"item\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/en\\\/stories-insights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/\",\"name\":\"Colombia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ldc.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor || Louis Dreyfus Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/","og_locale":"en_US","og_type":"article","og_title":"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor","og_description":"M\u00e1s conocida por sus tradiciones m\u00edsticas, desiertos dram\u00e1ticos, selvas y monta\u00f1as iridiscentes que se elevan por encima de los 5000 metros, la provincia de Jujuy tambi\u00e9n es una de las m\u00e1s pobres de Argentina. Cada a\u00f1o, los agricultores locales preparan platos festivos y los entierran en los campos como ofrendas a la Pachamama, la Diosa [&hellip;]","og_url":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/","og_site_name":"Colombia","article_modified_time":"2020-04-29T09:02:19+00:00","og_image":[{"width":506,"height":319,"url":"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/","url":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/","name":"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor || Louis Dreyfus Company","isPartOf":{"@id":"https:\/\/www.ldc.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/#primaryimage"},"image":{"@id":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg","datePublished":"2019-12-12T15:01:00+00:00","dateModified":"2020-04-29T09:02:19+00:00","breadcrumb":{"@id":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/#primaryimage","url":"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg","contentUrl":"https:\/\/www.ldc.com\/co\/wp-content\/uploads\/sites\/11\/Training-financial-inclusion-empowerment-for-improved-livelihoods-1.jpg","width":506,"height":319},{"@type":"BreadcrumbList","@id":"https:\/\/www.ldc.com\/co\/es\/stories-insights\/capacitacion-inclusion-financiera-y-empoderamiento-para-una-vida-mejor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ldc.com\/co\/en\/"},{"@type":"ListItem","position":2,"name":"Stories & Insights","item":"https:\/\/www.ldc.com\/co\/en\/stories-insights\/"},{"@type":"ListItem","position":3,"name":"Capacitaci\u00f3n, inclusi\u00f3n financiera y empoderamiento para una vida mejor"}]},{"@type":"WebSite","@id":"https:\/\/www.ldc.com\/co\/#website","url":"https:\/\/www.ldc.com\/co\/","name":"Colombia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ldc.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"lang":"es","translations":{"es":1825},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/stories-insight\/1825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/stories-insight"}],"about":[{"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/types\/stories-insight"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/comments?post=1825"}],"version-history":[{"count":3,"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/stories-insight\/1825\/revisions"}],"predecessor-version":[{"id":3565,"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/stories-insight\/1825\/revisions\/3565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/media\/1826"}],"wp:attachment":[{"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/media?parent=1825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/categories?post=1825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ldc.com\/co\/wp-json\/wp\/v2\/tags?post=1825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}